{"id":42276,"date":"2026-05-24T03:34:36","date_gmt":"2026-05-24T01:34:36","guid":{"rendered":"https:\/\/dizalica.hr\/pneumatske-dizalice\/pneumatische-hubgerate-fur-schwerste-lasten-bis-60-t-tmh-serie\/"},"modified":"2026-06-01T17:15:47","modified_gmt":"2026-06-01T15:15:47","slug":"pneumatische-schwerlast-hebezeuge","status":"publish","type":"page","link":"https:\/\/dizalica.hr\/de\/pneumatische-hebezeuge\/pneumatische-schwerlast-hebezeuge\/","title":{"rendered":"Pneumatische Hebezeuge f\u00fcr schwerste Lasten (bis 60 t) \u2013 TMH Serie"},"content":{"rendered":"\t\t<div data-elementor-type=\"wp-page\" data-elementor-id=\"42276\" class=\"elementor elementor-42276 elementor-41623\" data-elementor-post-type=\"page\">\n\t\t\t\t<div class=\"elementor-element elementor-element-1f893f0 e-con-full e-flex e-con e-parent\" data-id=\"1f893f0\" data-element_type=\"container\" data-e-type=\"container\">\n\t\t<div class=\"elementor-element elementor-element-8fb7f33 e-con-full e-flex e-con e-child\" data-id=\"8fb7f33\" data-element_type=\"container\" data-e-type=\"container\">\n\t\t<div class=\"elementor-element elementor-element-17177d2 e-con-full e-flex e-con e-child\" data-id=\"17177d2\" data-element_type=\"container\" data-e-type=\"container\">\n\t\t\t\t<div class=\"elementor-element elementor-element-a164a96 elementor-widget elementor-widget-heading\" data-id=\"a164a96\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<div class=\"elementor-heading-title elementor-size-default\"><a href=\"https:\/\/dizalica.hr\/de\/pneumatische-hebezeuge\/\" class=\"link1\">Pneumatische (Druckluft-) Hebeger\u00e4te<\/a><\/div>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-15e2b7c elementor-widget elementor-widget-heading\" data-id=\"15e2b7c\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h1 class=\"elementor-heading-title elementor-size-default\">Pneumatische Hebezeuge f\u00fcr schwerste Lasten (6\u201360 t) | Red Rooster TMH<\/h1>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t<div class=\"elementor-element elementor-element-84f7082 e-con-full e-flex e-con e-child\" data-id=\"84f7082\" data-element_type=\"container\" data-e-type=\"container\">\n\t\t<div class=\"elementor-element elementor-element-2136e2d e-con-full e-flex e-con e-child\" data-id=\"2136e2d\" data-element_type=\"container\" data-e-type=\"container\">\n\t\t\t\t<div class=\"elementor-element elementor-element-8f9c195 elementor-widget elementor-widget-text-editor\" data-id=\"8f9c195\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<p data-path-to-node=\"8\"><b data-path-to-node=\"8\" data-index-in-node=\"0\">Pneumatische Hebezeuge der TMH-Serie<\/b> repr\u00e4sentieren die Spitzenklasse f\u00fcr anspruchsvollste industrielle Einsatzbereiche. Entwickelt f\u00fcr den Einsatz unter extremen Bedingungen \u2013 von Werften und Offshore-Plattformen bis hin zu tiefen Bergwerken und schweren Gie\u00dfereien \u2013 erm\u00f6glichen diese Hebezeuge ein sicheres Handling von Lasten zwischen <b data-path-to-node=\"8\" data-index-in-node=\"279\">6 und 60 Tonnen<\/b>.<\/p><p data-path-to-node=\"8\">\u00a0<\/p><p data-path-to-node=\"9\">Die Konstruktion der Red Rooster TMH Hebezeuge basiert auf absoluter Zuverl\u00e4ssigkeit. W\u00e4hrend Elektromotoren bei solchen Belastungen und in aggressiven Umgebungen schnell \u00fcberhitzen w\u00fcrden, nutzt die TMH-Serie komprimierte Luft, die das System auf nat\u00fcrliche Weise k\u00fchlt und so einen <b data-path-to-node=\"9\" data-index-in-node=\"242\">endlosen Arbeitszyklus (100% Einschaltdauer)<\/b> unabh\u00e4ngig von der Arbeitsintensit\u00e4t gew\u00e4hrleistet.<\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t<div class=\"elementor-element elementor-element-8b0eff8 e-con-full e-flex e-con e-child\" data-id=\"8b0eff8\" data-element_type=\"container\" data-e-type=\"container\">\n\t\t\t\t<div class=\"elementor-element elementor-element-1651d99 elementor-widget elementor-widget-heading\" data-id=\"1651d99\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<div class=\"elementor-heading-title elementor-size-default\">Industriestandard: Un\u00fcbertroffene Zuverl\u00e4ssigkeit f\u00fcr Lasten von 500 kg bis 15 Tonnen.<\/div>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-ffa0ab3 elementor-widget-divider--view-line elementor-widget elementor-widget-divider\" data-id=\"ffa0ab3\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"divider.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<div class=\"elementor-divider\">\n\t\t\t<span class=\"elementor-divider-separator\">\n\t\t\t\t\t\t<\/span>\n\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-e347eba elementor-widget elementor-widget-text-editor\" data-id=\"e347eba\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<div class=\"nabrajanje\">\u2705 <b data-path-to-node=\"9,0,0\" data-index-in-node=\"0\">24\/7 Betriebszyklus<br \/><\/b>\u2705 <b data-path-to-node=\"9,1,0\" data-index-in-node=\"0\">ATEX-Sicherheit<br \/><\/b> \u2705 <b data-path-to-node=\"9,2,0\" data-index-in-node=\"0\">Pr\u00e4zise Steuerung<\/b><br \/>\u2705 <b data-path-to-node=\"9,4,0\" data-index-in-node=\"0\"><b data-path-to-node=\"9,4,0\" data-index-in-node=\"0\">Sicherheitsfaktor 5<br \/>\u2705 <\/b><\/b><b data-path-to-node=\"9,0,0\" data-index-in-node=\"0\">Tragf\u00e4higkeit:<\/b> 6 Tonnen \u2013 60 Tonnen (Standardmodelle)<\/div><div class=\"nabrajanje\">\u2705 <b data-path-to-node=\"12,1,0\" data-index-in-node=\"0\">Betriebsdruck \/ Luftverbrauch:<\/b> 6,3 bar \/ 80 \u2013 100 l\/s (bei den gr\u00f6\u00dften Modellen)<br \/><b data-path-to-node=\"9,2,0\" data-index-in-node=\"0\">\u2705\u00a0<\/b><b data-path-to-node=\"9,2,0\" data-index-in-node=\"0\">Sicherheit: <\/b>Integrierter \u00dcberlastschutz und \u201eFail-Safe\u201c-Automatikbremse.<br \/><b data-path-to-node=\"9,2,0\" data-index-in-node=\"0\">\u2705\u00a0<\/b><b data-path-to-node=\"12,3,0\" data-index-in-node=\"0\">Geh\u00e4use:<\/b> Stahlgeh\u00e4use mit hoher Korrosions- und Sto\u00dffestigkeit.<\/div>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-da8dc28 elementor-widget-divider--separator-type-pattern elementor-widget-divider--view-line elementor-widget elementor-widget-divider\" data-id=\"da8dc28\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"divider.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<div class=\"elementor-divider\" style=\"--divider-pattern-url: url(&quot;data:image\/svg+xml,%3Csvg xmlns=&#039;http:\/\/www.w3.org\/2000\/svg&#039; preserveAspectRatio=&#039;none&#039; overflow=&#039;visible&#039; height=&#039;100%&#039; viewBox=&#039;0 0 24 24&#039; fill=&#039;black&#039; stroke=&#039;none&#039;%3E%3Cpolygon points=&#039;9.4,2 24,2 14.6,21.6 0,21.6&#039;\/%3E%3C\/svg%3E&quot;);\">\n\t\t\t<span class=\"elementor-divider-separator\">\n\t\t\t\t\t\t<\/span>\n\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-55f6517 elementor-widget elementor-widget-text-editor\" data-id=\"55f6517\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<h2 class=\"nabrajanje\">Angebot an pneumatischen Hebezeugen f\u00fcr schwerste Lasten<\/h2>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-b3a0538 etheme-elementor-products-equal-height etheme-elementor-product-align-center elementor-widget elementor-widget-etheme_product_grid\" data-id=\"b3a0538\" data-element_type=\"widget\" data-e-type=\"widget\" data-settings=\"{&quot;cols_mobile&quot;:&quot;1&quot;,&quot;cols_gap&quot;:{&quot;unit&quot;:&quot;px&quot;,&quot;size&quot;:10,&quot;sizes&quot;:[]},&quot;rows_gap&quot;:{&quot;unit&quot;:&quot;px&quot;,&quot;size&quot;:10,&quot;sizes&quot;:[]},&quot;product_attributes&quot;:&quot;yes&quot;,&quot;_animation&quot;:&quot;none&quot;,&quot;cols&quot;:&quot;3&quot;,&quot;query_type&quot;:&quot;all&quot;,&quot;navigation&quot;:&quot;none&quot;,&quot;cols_gap_tablet&quot;:{&quot;unit&quot;:&quot;px&quot;,&quot;size&quot;:&quot;&quot;,&quot;sizes&quot;:[]},&quot;cols_gap_mobile&quot;:{&quot;unit&quot;:&quot;px&quot;,&quot;size&quot;:&quot;&quot;,&quot;sizes&quot;:[]},&quot;rows_gap_tablet&quot;:{&quot;unit&quot;:&quot;px&quot;,&quot;size&quot;:&quot;&quot;,&quot;sizes&quot;:[]},&quot;rows_gap_mobile&quot;:{&quot;unit&quot;:&quot;px&quot;,&quot;size&quot;:&quot;&quot;,&quot;sizes&quot;:[]}}\" data-widget_type=\"etheme_product_grid.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<div class=\"woocommerce-info\">Es wurden keine Produkte gefunden, die deiner Auswahl entsprechen.<\/div>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t<div class=\"elementor-element elementor-element-2c30ed5 e-con-full e-flex e-con e-child\" data-id=\"2c30ed5\" data-element_type=\"container\" data-e-type=\"container\">\n\t\t<div class=\"elementor-element elementor-element-b290cf4 e-con-full e-flex e-con e-child\" data-id=\"b290cf4\" data-element_type=\"container\" data-e-type=\"container\">\n\t\t\t\t<div class=\"elementor-element elementor-element-688b43a elementor-widget elementor-widget-spacer\" data-id=\"688b43a\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"spacer.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<div class=\"elementor-spacer\">\n\t\t\t<div class=\"elementor-spacer-inner\"><\/div>\n\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-62a43fe elementor-widget-divider--separator-type-pattern elementor-widget-divider--view-line elementor-widget elementor-widget-divider\" data-id=\"62a43fe\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"divider.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<div class=\"elementor-divider\" style=\"--divider-pattern-url: url(&quot;data:image\/svg+xml,%3Csvg xmlns=&#039;http:\/\/www.w3.org\/2000\/svg&#039; preserveAspectRatio=&#039;none&#039; overflow=&#039;visible&#039; height=&#039;100%&#039; viewBox=&#039;0 0 24 24&#039; fill=&#039;black&#039; stroke=&#039;none&#039;%3E%3Cpolygon points=&#039;9.4,2 24,2 14.6,21.6 0,21.6&#039;\/%3E%3C\/svg%3E&quot;);\">\n\t\t\t<span class=\"elementor-divider-separator\">\n\t\t\t\t\t\t<\/span>\n\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-e11cf51 elementor-widget elementor-widget-text-editor\" data-id=\"e11cf51\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<h2 class=\"nabrajanje\">Vergleichstabelle der pneumatischen Hebezeuge f\u00fcr schwerste Lasten<\/h2>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-8afca33 elementor-widget elementor-widget-text-editor\" data-id=\"8afca33\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<div class=\"table-wrap\" style=\"width: 98%; margin: 0 auto;\"><table class=\"styled-table\" role=\"table\" aria-label=\"Vergleichstabelle TMH Pneumatik-Hebeger\u00e4te\"><thead><tr><th>Modell<\/th><th>\u2696\ufe0f <br \/><br \/>Tragf\u00e4higkeit<\/th><th>\ud83c\udf9b\ufe0f <br \/><br \/>Steuerung<\/th><th>\ud83d\udee2\ufe0f <br \/><br \/>Schmierung<\/th><th>\u2b06\ufe0f <br \/><br \/>Hebegeschwindigkeit<br \/>(mit Last \/ ohne Last)<\/th><th>\u2b07\ufe0f <br \/><br \/>Senkgeschwindigkeit<br \/>(mit Last)<\/th><th>\u2699\ufe0f <br \/><br \/>Gewicht (3 m Kette)<\/th><th>\ud83d\udd17 <br \/><br \/>Kettenstr\u00e4nge + Kettentyp<\/th><\/tr><\/thead><tbody><tr><td>TMH\u20113000C<\/td><td>3000 kg<\/td><td>Seil<\/td><td>AC60\u2011F10DM\u20118\u2011B<\/td><td>5,4 \/ 10,8 m\/min<\/td><td>10,2 m\/min<\/td><td>99 kg<\/td><td>1 (13 \u00d7 36 mm)<\/td><\/tr><tr><td>TMH\u20113000LFC<\/td><td>3000 kg<\/td><td>Seil<\/td><td>ohne Behandlung<\/td><td>3,1 \/ 6,4 m\/min<\/td><td>2,8 m\/min<\/td><td>99 kg<\/td><td>1 (13 \u00d7 36 mm)<\/td><\/tr><tr><td>TMH\u20113000LFPE<\/td><td>3000 kg<\/td><td>Taster<\/td><td>ohne Behandlung<\/td><td>3,1 \/ 6,4 m\/min<\/td><td>2,8 m\/min<\/td><td>99 kg<\/td><td>1 (13 \u00d7 36 mm)<\/td><\/tr><tr><td>TMH\u20113000PE<\/td><td>3000 kg<\/td><td>Taster<\/td><td>AC60\u2011F10DM\u20118\u2011B<\/td><td>5,4 \/ 10,8 m\/min<\/td><td>10,2 m\/min<\/td><td>99 kg<\/td><td>1 (13 \u00d7 36 mm)<\/td><\/tr><tr><td>TMH\u20116000C2<\/td><td>6000 kg<\/td><td>Seil<\/td><td>AC60\u2011F10DM\u20118\u2011B<\/td><td>2,7 \/ 5,4 m\/min<\/td><td>5,1 m\/min<\/td><td>124 kg<\/td><td>2 (13 \u00d7 36 mm)<\/td><\/tr><tr><td>TMH\u20116000LFC2<\/td><td>6000 kg<\/td><td>Seil<\/td><td>ohne Behandlung<\/td><td>1,6 \/ 3,2 m\/min<\/td><td>2,8 m\/min<\/td><td>124 kg<\/td><td>2 (13 \u00d7 36 mm)<\/td><\/tr><tr><td>TMH\u20116000LFP2E<\/td><td>6000 kg<\/td><td>Taster<\/td><td>ohne Behandlung<\/td><td>1,6 \/ 3,2 m\/min<\/td><td>2,8 m\/min<\/td><td>124 kg<\/td><td>2 (13 \u00d7 36 mm)<\/td><\/tr><tr><td>TMH\u20116000P2E<\/td><td>6000 kg<\/td><td>Taster<\/td><td>AC60\u2011F10DM\u20118\u2011B<\/td><td>2,7 \/ 5,4 m\/min<\/td><td>5,1 m\/min<\/td><td>124 kg<\/td><td>2 (13 \u00d7 36 mm)<\/td><\/tr><tr><td>TMH\u20119000C3<\/td><td>9000 kg<\/td><td>Seil<\/td><td>AC60\u2011F10DM\u20118\u2011B<\/td><td>1,8 \/ 3,6 m\/min<\/td><td>3,4 m\/min<\/td><td>170 kg<\/td><td>3 (13 \u00d7 36 mm)<\/td><\/tr><tr><td>TMH\u20119000LFC3<\/td><td>9000 kg<\/td><td>Seil<\/td><td>ohne Behandlung<\/td><td>1,0 \/ 2,1 m\/min<\/td><td>1,9 m\/min<\/td><td>170 kg<\/td><td>3 (13 \u00d7 36 mm)<\/td><\/tr><tr><td>TMH\u201110C2<\/td><td>10000 kg<\/td><td>Seil<\/td><td>AC60\u2011F10DM\u20118\u2011B<\/td><td>1,6 \/ 3,3 m\/min<\/td><td>3,2 m\/min<\/td><td>206 kg<\/td><td>2 (16 \u00d7 45 mm)<\/td><\/tr><tr><td>TMH\u201110P2E<\/td><td>10000 kg<\/td><td>Taster<\/td><td>AC60\u2011F10DM\u20118\u2011B<\/td><td>1,6 \/ 3,3 m\/min<\/td><td>3,2 m\/min<\/td><td>206 kg<\/td><td>2 (16 \u00d7 45 mm)<\/td><\/tr><tr><td>TMH\u201112000C4<\/td><td>12000 kg<\/td><td>Seil<\/td><td>AC60\u2011F10DM\u20118\u2011B<\/td><td>1,35 \/ 2,7 m\/min<\/td><td>2,55 m\/min<\/td><td>210 kg<\/td><td>4 (13 \u00d7 36 mm)<\/td><\/tr><tr><td>TMH\u201112000LFC4<\/td><td>12000 kg<\/td><td>Seil<\/td><td>ohne Behandlung<\/td><td>0,8 \/ 1,6 m\/min<\/td><td>1,4 m\/min<\/td><td>210 kg<\/td><td>4 (13 \u00d7 36 mm)<\/td><\/tr><tr><td>TMH\u201115000C5<\/td><td>15000 kg<\/td><td>Seil<\/td><td>AC60\u2011F10DM\u20118\u2011B<\/td><td>1,08 \/ 2,16 m\/min<\/td><td>2,04 m\/min<\/td><td>280 kg<\/td><td>5 (13 \u00d7 36 mm)<\/td><\/tr><tr><td>TMH\u201115000LFC5<\/td><td>15000 kg<\/td><td>Seil<\/td><td>ohne Behandlung<\/td><td>0,6 \/ 1,3 m\/min<\/td><td>1,1 m\/min<\/td><td>280 kg<\/td><td>5 (13 \u00d7 36 mm)<\/td><\/tr><tr><td>TMH\u201115C3<\/td><td>15000 kg<\/td><td>Seil<\/td><td>AC60\u2011F10DM\u20118\u2011B<\/td><td>1,05 \/ 2,2 m\/min<\/td><td>2,1 m\/min<\/td><td>316 kg<\/td><td>3 (16 \u00d7 45 mm)<\/td><\/tr><tr><td>TMH\u201115P3E<\/td><td>15000 kg<\/td><td>Taster<\/td><td>AC60\u2011F10DM\u20118\u2011B<\/td><td>1,05 \/ 2,2 m\/min<\/td><td>2,1 m\/min<\/td><td>316 kg<\/td><td>3 (16 \u00d7 45 mm)<\/td><\/tr><tr><td>TMH\u201120C4<\/td><td>20000 kg<\/td><td>Seil<\/td><td>AC60\u2011F10DM\u20118\u2011B<\/td><td>0,8 \/ 1,6 m\/min<\/td><td>1,6 m\/min<\/td><td>466 kg<\/td><td>4 (16 \u00d7 45 mm)<\/td><\/tr><tr><td>TMH\u201120P4E<\/td><td>20000 kg<\/td><td>Taster<\/td><td>AC60\u2011F10DM\u20118\u2011B<\/td><td>0,8 \/ 1,6 m\/min<\/td><td>1,6 m\/min<\/td><td>466 kg<\/td><td>4 (16 \u00d7 45 mm)<\/td><\/tr><tr><td>TMH\u201125C2<\/td><td>25000 kg<\/td><td>Seil<\/td><td>AC60\u2011F10DM\u20118\u2011B<\/td><td>1,4 \/ 2,7 m\/min<\/td><td>3,0 m\/min<\/td><td>581 kg<\/td><td>2 (23,5 \u00d7 66 mm)<\/td><\/tr><tr><td>TMH\u201125P2E<\/td><td>25000 kg<\/td><td>Taster<\/td><td>AC60\u2011F10DM\u20118\u2011B<\/td><td>1,4 \/ 2,7 m\/min<\/td><td>3,0 m\/min<\/td><td>581 kg<\/td><td>2 (23,5 \u00d7 66 mm)<\/td><\/tr><tr><td>TMH\u201130C2<\/td><td>30000 kg<\/td><td>Seil<\/td><td>AC60\u2011F10DM\u20118\u2011B<\/td><td>1,0 \/ 2,7 m\/min<\/td><td>2,7 m\/min<\/td><td>581 kg<\/td><td>2 (23,5 \u00d7 66 mm)<\/td><\/tr><tr><td>TMH\u201130P2E<\/td><td>30000 kg<\/td><td>Taster<\/td><td>AC60\u2011F10DM\u20118\u2011B<\/td><td>1,0 \/ 2,7 m\/min<\/td><td>2,7 m\/min<\/td><td>581 kg<\/td><td>2 (23,5 \u00d7 66 mm)<\/td><\/tr><tr><td>TMH\u201137C3<\/td><td>37500 kg<\/td><td>Seil<\/td><td>AC60\u2011F10DM\u20118\u2011B<\/td><td>0,9 \/ 1,8 m\/min<\/td><td>2,0 m\/min<\/td><td>1300 kg<\/td><td>3 (23,5 \u00d7 66 mm)<\/td><\/tr><tr><td>TMH\u201137P3E<\/td><td>37500 kg<\/td><td>Taster<\/td><td>AC60\u2011F10DM\u20118\u2011B<\/td><td>0,9 \/ 1,8 m\/min<\/td><td>2,0 m\/min<\/td><td>1300 kg<\/td><td>3 (23,5 \u00d7 66 mm)<\/td><\/tr><tr><td>TMH\u201145C3<\/td><td>45000 kg<\/td><td>Seil<\/td><td>AC60\u2011F10DM\u20118\u2011B<\/td><td>0,65 \/ 1,8 m\/min<\/td><td>1,8 m\/min<\/td><td>1300 kg<\/td><td>3 (23,5 \u00d7 66 mm)<\/td><\/tr><tr><td>TMH\u201145P3E<\/td><td>45000 kg<\/td><td>Taster<\/td><td>AC60\u2011F10DM\u20118\u2011B<\/td><td>0,65 \/ 1,8 m\/min<\/td><td>1,8 m\/min<\/td><td>1300 kg<\/td><td>3 (23,5 \u00d7 66 mm)<\/td><\/tr><tr><td>TMH\u201150C4<\/td><td>50000 kg<\/td><td>Seil<\/td><td>AC60\u2011F10DM\u20118\u2011B<\/td><td>0,7 \/ 1,3 m\/min<\/td><td>1,5 m\/min<\/td><td>1800 kg<\/td><td>4 (23,5 \u00d7 66 mm)<\/td><\/tr><tr><td>TMH\u201150P4E<\/td><td>50000 kg<\/td><td>Taster<\/td><td>AC60\u2011F10DM\u20118\u2011B<\/td><td>0,7 \/ 1,3 m\/min<\/td><td>1,5 m\/min<\/td><td>1800 kg<\/td><td>4 (23,5 \u00d7 66 mm)<\/td><\/tr><tr><td>TMH\u201160C4<\/td><td>60000 kg<\/td><td>Seil<\/td><td>AC60\u2011F10DM\u20118\u2011B<\/td><td>0,5 \/ 1,3 m\/min<\/td><td>1,3 m\/min<\/td><td>* kg<\/td><td>4 (23,5 \u00d7 66 mm)<\/td><\/tr><tr><td>TMH\u201160P4E<\/td><td>60000 kg<\/td><td>Taster<\/td><td>AC60\u2011F10DM\u20118\u2011B<\/td><td>0,5 \/ 1,3 m\/min<\/td><td>1,3 m\/min<\/td><td>* kg<\/td><td>4 (23,5 \u00d7 66 mm)<\/td><\/tr><\/tbody><\/table><\/div>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-09b6567 elementor-widget-divider--separator-type-pattern elementor-widget-divider--view-line elementor-widget elementor-widget-divider\" data-id=\"09b6567\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"divider.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<div class=\"elementor-divider\" style=\"--divider-pattern-url: url(&quot;data:image\/svg+xml,%3Csvg xmlns=&#039;http:\/\/www.w3.org\/2000\/svg&#039; preserveAspectRatio=&#039;none&#039; overflow=&#039;visible&#039; height=&#039;100%&#039; viewBox=&#039;0 0 24 24&#039; fill=&#039;black&#039; stroke=&#039;none&#039;%3E%3Cpolygon points=&#039;9.4,2 24,2 14.6,21.6 0,21.6&#039;\/%3E%3C\/svg%3E&quot;);\">\n\t\t\t<span class=\"elementor-divider-separator\">\n\t\t\t\t\t\t<\/span>\n\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t<div class=\"elementor-element elementor-element-32198be e-con-full e-flex e-con e-child\" data-id=\"32198be\" data-element_type=\"container\" data-e-type=\"container\">\n\t\t<div class=\"elementor-element elementor-element-2bb932c e-con-full e-flex e-con e-child\" data-id=\"2bb932c\" data-element_type=\"container\" data-e-type=\"container\">\n\t\t\t\t<div class=\"elementor-element elementor-element-d4e581c elementor-widget elementor-widget-text-editor\" data-id=\"d4e581c\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<h2 data-path-to-node=\"2\">F\u00fcr das Unm\u00f6gliche konstruiert: Kraft ohne Kompromisse<\/h2><p data-path-to-node=\"3\">Wenn Standardausr\u00fcstung an ihre Grenzen st\u00f6\u00dft, kommt die <b data-path-to-node=\"3\" data-index-in-node=\"54\">TMH Serie<\/b> zum Einsatz. Diese Krane sind nicht einfach gr\u00f6\u00dfere Versionen der Standardmodelle; sie sind das Ergebnis erstklassiger Ingenieurskunst, entwickelt f\u00fcr extreme Lasten. Jede Komponente \u2013 von der massiven geschmiedeten Kette bis zum pr\u00e4zise gefertigten Druckluftmotor \u2013 ist darauf ausgelegt, h\u00e4rtesten Bedingungen standzuhalten, die jedes andere Hebesystem zerst\u00f6ren w\u00fcrden.<\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-5f3a750 elementor-widget elementor-widget-text-editor\" data-id=\"5f3a750\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<h2 data-path-to-node=\"4\">Warum ist die TMH-Serie die erste Wahl in der Schwerindustrie?<\/h2><ul data-path-to-node=\"5\"><li><p data-path-to-node=\"5,0,0\"><b data-path-to-node=\"5,0,0\" data-index-in-node=\"0\">Thermische Stabilit\u00e4t:<\/b> W\u00e4hrend sich Elektromotoren beim Heben von 30 oder 50 Tonnen stark erhitzen und Pausen ben\u00f6tigen, bleibt der Druckluftmotor der TMH-Hebez\u00fcge auch nach stundenlangem Dauerbetrieb k\u00fchl.<\/p><\/li><li><p data-path-to-node=\"5,1,0\"><b data-path-to-node=\"5,1,0\" data-index-in-node=\"0\">Absolute Pr\u00e4zision in der &#8222;Schwergewichtsklasse&#8220;:<\/b> Das Heben von Lasten bis zu 60 Tonnen erfordert h\u00f6chste Pr\u00e4zision. Die Red Rooster TMH-Hebez\u00fcge erm\u00f6glichen dem Bediener eine millimetergenaue Steuerung und minimieren so das Risiko von Besch\u00e4digungen teurer Anlagen bei der Montage.<\/p><\/li><li><p data-path-to-node=\"5,2,0\"><b data-path-to-node=\"5,2,0\" data-index-in-node=\"0\">Minimaler Wartungsaufwand unter extremen Bedingungen:<\/b> Mit weniger beweglichen Teilen als elektrische Alternativen konzipiert, ben\u00f6tigen TMH-Hebez\u00fcge nur minimale Wartung \u2013 selbst bei Einsatz in salzhaltiger Luft, Minenstaub oder extremer Hitze in Gie\u00dfereien.<\/p><\/li><\/ul><blockquote data-path-to-node=\"6\"><p data-path-to-node=\"6,0\"><b data-path-to-node=\"6,0\" data-index-in-node=\"0\">&#8222;Wenn Sicherheit oberste Priorit\u00e4t hat und die Lasten in Dutzenden von Tonnen gemessen werden, ist die Red Rooster TMH-Serie die einzige L\u00f6sung, auf die Sie sich zu 100 % verlassen k\u00f6nnen.&#8220;<\/b><\/p><\/blockquote>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t<div class=\"elementor-element elementor-element-0a4eb13 e-con-full e-flex e-con e-child\" data-id=\"0a4eb13\" data-element_type=\"container\" data-e-type=\"container\">\n\t\t\t\t<div class=\"elementor-element elementor-element-db018e6 elementor-widget elementor-widget-text-editor\" data-id=\"db018e6\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<div class=\"nabrajanje\"><h3 data-path-to-node=\"8\">Red Rooster TMH \u2013 Ideale Einsatzbereiche:<\/h3><ul data-path-to-node=\"9\"><li><p data-path-to-node=\"9,0,0\"><b data-path-to-node=\"9,0,0\" data-index-in-node=\"0\">Schiffbau:<\/b> Montage von Schiffsektionen und Einbau massiver Schiffsmotoren.<\/p><\/li><li><p data-path-to-node=\"9,1,0\"><b data-path-to-node=\"9,1,0\" data-index-in-node=\"0\">\u00d6l- und Gasindustrie:<\/b> Arbeiten auf Plattformen und in Raffinerien, bei denen ATEX-Sicherheit oberste Priorit\u00e4t hat.<\/p><\/li><li><p data-path-to-node=\"9,2,0\"><b data-path-to-node=\"9,2,0\" data-index-in-node=\"0\">Bergbau:<\/b> Herausziehen schwerer Maschinen und Arbeiten in unterirdischen Sch\u00e4chten.<\/p><\/li><li><p data-path-to-node=\"9,3,0\"><b data-path-to-node=\"9,3,0\" data-index-in-node=\"0\">Energiewirtschaft:<\/b> Montage und Wartung von Turbinen in Wasser- und W\u00e4rmekraftwerken.<\/p><\/li><\/ul><\/div>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-33a16c3 elementor-widget elementor-widget-text-editor\" data-id=\"33a16c3\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<h2 class=\"nabrajanje\">H\u00e4ufig gestellte Fragen<\/h2>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-e3a61a6 elementor-widget elementor-widget-n-accordion\" data-id=\"e3a61a6\" data-element_type=\"widget\" data-e-type=\"widget\" data-settings=\"{&quot;default_state&quot;:&quot;all_collapsed&quot;,&quot;max_items_expended&quot;:&quot;one&quot;,&quot;n_accordion_animation_duration&quot;:{&quot;unit&quot;:&quot;ms&quot;,&quot;size&quot;:400,&quot;sizes&quot;:[]}}\" data-widget_type=\"nested-accordion.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<div class=\"e-n-accordion\" aria-label=\"Accordion. Open links with Enter or Space, close with Escape, and navigate with Arrow Keys\">\n\t\t\t\t\t\t<details id=\"e-n-accordion-item-2380\" class=\"e-n-accordion-item\" >\n\t\t\t\t<summary class=\"e-n-accordion-item-title\" data-accordion-index=\"1\" tabindex=\"0\" aria-expanded=\"false\" aria-controls=\"e-n-accordion-item-2380\" >\n\t\t\t\t\t<span class='e-n-accordion-item-title-header'><h3 class=\"e-n-accordion-item-title-text\"> K\u00f6nnen TMH-Krane auch unter Wasser oder auf Offshore-\u00d6lplattformen eingesetzt werden? <\/h3><\/span>\n\t\t\t\t\t\t\t<span class='e-n-accordion-item-title-icon'>\n\t\t\t<span class='e-opened' ><svg aria-hidden=\"true\" class=\"e-font-icon-svg e-fas-minus\" viewBox=\"0 0 448 512\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\"><path d=\"M416 208H32c-17.67 0-32 14.33-32 32v32c0 17.67 14.33 32 32 32h384c17.67 0 32-14.33 32-32v-32c0-17.67-14.33-32-32-32z\"><\/path><\/svg><\/span>\n\t\t\t<span class='e-closed'><svg aria-hidden=\"true\" class=\"e-font-icon-svg e-fas-plus\" viewBox=\"0 0 448 512\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\"><path d=\"M416 208H272V64c0-17.67-14.33-32-32-32h-32c-17.67 0-32 14.33-32 32v144H32c-17.67 0-32 14.33-32 32v32c0 17.67 14.33 32 32 32h144v144c0 17.67 14.33 32 32 32h32c17.67 0 32-14.33 32-32V304h144c17.67 0 32-14.33 32-32v-32c0-17.67-14.33-32-32-32z\"><\/path><\/svg><\/span>\n\t\t<\/span>\n\n\t\t\t\t\t\t<\/summary>\n\t\t\t\t<div role=\"region\" aria-labelledby=\"e-n-accordion-item-2380\" class=\"elementor-element elementor-element-8895ee2 e-con-full e-flex e-con e-child\" data-id=\"8895ee2\" data-element_type=\"container\" data-e-type=\"container\">\n\t\t\t\t<div class=\"elementor-element elementor-element-d3f6a6a elementor-widget elementor-widget-text-editor\" data-id=\"d3f6a6a\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<div class=\"nabrajanje\">Ja. Die TMH-Serie ist die \u201eerste Wahl\u201c f\u00fcr die Offshore-Industrie. Aufgrund des Fehlens von Elektronik und des robusten Stahlgeh\u00e4uses sind sie ideal f\u00fcr salzhaltige, feuchte und korrosive Umgebungen. Sie sind mit vollst\u00e4ndigem ATEX-Schutz f\u00fcr explosionsgef\u00e4hrdete Bereiche erh\u00e4ltlich.<\/div>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/details>\n\t\t\t\t\t\t<details id=\"e-n-accordion-item-2381\" class=\"e-n-accordion-item\" >\n\t\t\t\t<summary class=\"e-n-accordion-item-title\" data-accordion-index=\"2\" tabindex=\"-1\" aria-expanded=\"false\" aria-controls=\"e-n-accordion-item-2381\" >\n\t\t\t\t\t<span class='e-n-accordion-item-title-header'><h3 class=\"e-n-accordion-item-title-text\"> Wie viel Druckluft wird f\u00fcr den Betrieb eines 60-Tonnen-Hebers ben\u00f6tigt? <\/h3><\/span>\n\t\t\t\t\t\t\t<span class='e-n-accordion-item-title-icon'>\n\t\t\t<span class='e-opened' ><svg aria-hidden=\"true\" class=\"e-font-icon-svg e-fas-minus\" viewBox=\"0 0 448 512\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\"><path d=\"M416 208H32c-17.67 0-32 14.33-32 32v32c0 17.67 14.33 32 32 32h384c17.67 0 32-14.33 32-32v-32c0-17.67-14.33-32-32-32z\"><\/path><\/svg><\/span>\n\t\t\t<span class='e-closed'><svg aria-hidden=\"true\" class=\"e-font-icon-svg e-fas-plus\" viewBox=\"0 0 448 512\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\"><path d=\"M416 208H272V64c0-17.67-14.33-32-32-32h-32c-17.67 0-32 14.33-32 32v144H32c-17.67 0-32 14.33-32 32v32c0 17.67 14.33 32 32 32h144v144c0 17.67 14.33 32 32 32h32c17.67 0 32-14.33 32-32V304h144c17.67 0 32-14.33 32-32v-32c0-17.67-14.33-32-32-32z\"><\/path><\/svg><\/span>\n\t\t<\/span>\n\n\t\t\t\t\t\t<\/summary>\n\t\t\t\t<div role=\"region\" aria-labelledby=\"e-n-accordion-item-2381\" class=\"elementor-element elementor-element-6d62a31 e-con-full e-flex e-con e-child\" data-id=\"6d62a31\" data-element_type=\"container\" data-e-type=\"container\">\n\t\t\t\t<div class=\"elementor-element elementor-element-0e122c9 elementor-widget elementor-widget-text-editor\" data-id=\"0e122c9\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<div class=\"nabrajanje\">Diese Systeme erfordern eine leistungsf\u00e4hige Druckluftinstallation. Der Verbrauch liegt bei voller Auslastung bei etwa 100 l\/s. Es wird empfohlen, Luftspeicher in der N\u00e4he des Krans zu verwenden, um einen stabilen Druck w\u00e4hrend des kontinuierlichen Hebens zu gew\u00e4hrleisten.<\/div>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/details>\n\t\t\t\t\t\t<details id=\"e-n-accordion-item-2382\" class=\"e-n-accordion-item\" >\n\t\t\t\t<summary class=\"e-n-accordion-item-title\" data-accordion-index=\"3\" tabindex=\"-1\" aria-expanded=\"false\" aria-controls=\"e-n-accordion-item-2382\" >\n\t\t\t\t\t<span class='e-n-accordion-item-title-header'><h3 class=\"e-n-accordion-item-title-text\"> Gibt es ein Not-Aus-System f\u00fcr den Fall eines Luftausfalls? <\/h3><\/span>\n\t\t\t\t\t\t\t<span class='e-n-accordion-item-title-icon'>\n\t\t\t<span class='e-opened' ><svg aria-hidden=\"true\" class=\"e-font-icon-svg e-fas-minus\" viewBox=\"0 0 448 512\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\"><path d=\"M416 208H32c-17.67 0-32 14.33-32 32v32c0 17.67 14.33 32 32 32h384c17.67 0 32-14.33 32-32v-32c0-17.67-14.33-32-32-32z\"><\/path><\/svg><\/span>\n\t\t\t<span class='e-closed'><svg aria-hidden=\"true\" class=\"e-font-icon-svg e-fas-plus\" viewBox=\"0 0 448 512\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\"><path d=\"M416 208H272V64c0-17.67-14.33-32-32-32h-32c-17.67 0-32 14.33-32 32v144H32c-17.67 0-32 14.33-32 32v32c0 17.67 14.33 32 32 32h144v144c0 17.67 14.33 32 32 32h32c17.67 0 32-14.33 32-32V304h144c17.67 0 32-14.33 32-32v-32c0-17.67-14.33-32-32-32z\"><\/path><\/svg><\/span>\n\t\t<\/span>\n\n\t\t\t\t\t\t<\/summary>\n\t\t\t\t<div role=\"region\" aria-labelledby=\"e-n-accordion-item-2382\" class=\"elementor-element elementor-element-aa8b7f2 e-con-full e-flex e-con e-child\" data-id=\"aa8b7f2\" data-element_type=\"container\" data-e-type=\"container\">\n\t\t\t\t<div class=\"elementor-element elementor-element-db427f9 elementor-widget elementor-widget-text-editor\" data-id=\"db427f9\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<div class=\"nabrajanje\">Absolut. Jeder Red Rooster TMH Kettenzug ist mit einer automatischen Scheibenbremse ausgestattet, die mechanisch aktiviert wird (schlie\u00dft), sobald der Luftdruck abf\u00e4llt oder die Steuerung losgelassen wird. Die Last bleibt in ihrer aktuellen Position sicher blockiert.<\/div>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/details>\n\t\t\t\t\t\t<details id=\"e-n-accordion-item-2383\" class=\"e-n-accordion-item\" >\n\t\t\t\t<summary class=\"e-n-accordion-item-title\" data-accordion-index=\"4\" tabindex=\"-1\" aria-expanded=\"false\" aria-controls=\"e-n-accordion-item-2383\" >\n\t\t\t\t\t<span class='e-n-accordion-item-title-header'><h3 class=\"e-n-accordion-item-title-text\"> Ist ein pr\u00e4zises Absenken von Lasten mit 30 oder 50 Tonnen m\u00f6glich? <\/h3><\/span>\n\t\t\t\t\t\t\t<span class='e-n-accordion-item-title-icon'>\n\t\t\t<span class='e-opened' ><svg aria-hidden=\"true\" class=\"e-font-icon-svg e-fas-minus\" viewBox=\"0 0 448 512\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\"><path d=\"M416 208H32c-17.67 0-32 14.33-32 32v32c0 17.67 14.33 32 32 32h384c17.67 0 32-14.33 32-32v-32c0-17.67-14.33-32-32-32z\"><\/path><\/svg><\/span>\n\t\t\t<span class='e-closed'><svg aria-hidden=\"true\" class=\"e-font-icon-svg e-fas-plus\" viewBox=\"0 0 448 512\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\"><path d=\"M416 208H272V64c0-17.67-14.33-32-32-32h-32c-17.67 0-32 14.33-32 32v144H32c-17.67 0-32 14.33-32 32v32c0 17.67 14.33 32 32 32h144v144c0 17.67 14.33 32 32 32h32c17.67 0 32-14.33 32-32V304h144c17.67 0 32-14.33 32-32v-32c0-17.67-14.33-32-32-32z\"><\/path><\/svg><\/span>\n\t\t<\/span>\n\n\t\t\t\t\t\t<\/summary>\n\t\t\t\t<div role=\"region\" aria-labelledby=\"e-n-accordion-item-2383\" class=\"elementor-element elementor-element-5928d00 e-con-full e-flex e-con e-child\" data-id=\"5928d00\" data-element_type=\"container\" data-e-type=\"container\">\n\t\t\t\t<div class=\"elementor-element elementor-element-2e0a8ed elementor-widget elementor-widget-text-editor\" data-id=\"2e0a8ed\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<div class=\"nabrajanje\">Obwohl sie massiv sind, verwenden TMH-Krane hochpr\u00e4zise proportionale Ventile. Das bedeutet, dass der Bediener eine Last von 60 Tonnen mit einer Geschwindigkeit von nur wenigen Millimetern pro Sekunde bewegen kann \u2013 ein entscheidender Vorteil bei der Montage von Schiffsmotoren oder Turbinen.<\/div>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/details>\n\t\t\t\t\t\t<details id=\"e-n-accordion-item-2384\" class=\"e-n-accordion-item\" >\n\t\t\t\t<summary class=\"e-n-accordion-item-title\" data-accordion-index=\"5\" tabindex=\"-1\" aria-expanded=\"false\" aria-controls=\"e-n-accordion-item-2384\" >\n\t\t\t\t\t<span class='e-n-accordion-item-title-header'><h3 class=\"e-n-accordion-item-title-text\"> Kann der Kran auf einem Fahrwerk (Trolley) f\u00fcr seitliche Bewegung montiert werden? <\/h3><\/span>\n\t\t\t\t\t\t\t<span class='e-n-accordion-item-title-icon'>\n\t\t\t<span class='e-opened' ><svg aria-hidden=\"true\" class=\"e-font-icon-svg e-fas-minus\" viewBox=\"0 0 448 512\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\"><path d=\"M416 208H32c-17.67 0-32 14.33-32 32v32c0 17.67 14.33 32 32 32h384c17.67 0 32-14.33 32-32v-32c0-17.67-14.33-32-32-32z\"><\/path><\/svg><\/span>\n\t\t\t<span class='e-closed'><svg aria-hidden=\"true\" class=\"e-font-icon-svg e-fas-plus\" viewBox=\"0 0 448 512\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\"><path d=\"M416 208H272V64c0-17.67-14.33-32-32-32h-32c-17.67 0-32 14.33-32 32v144H32c-17.67 0-32 14.33-32 32v32c0 17.67 14.33 32 32 32h144v144c0 17.67 14.33 32 32 32h32c17.67 0 32-14.33 32-32V304h144c17.67 0 32-14.33 32-32v-32c0-17.67-14.33-32-32-32z\"><\/path><\/svg><\/span>\n\t\t<\/span>\n\n\t\t\t\t\t\t<\/summary>\n\t\t\t\t<div role=\"region\" aria-labelledby=\"e-n-accordion-item-2384\" class=\"elementor-element elementor-element-6c61e62 e-con-full e-flex e-con e-child\" data-id=\"6c61e62\" data-element_type=\"container\" data-e-type=\"container\">\n\t\t\t\t<div class=\"elementor-element elementor-element-403798b elementor-widget elementor-widget-text-editor\" data-id=\"403798b\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<div class=\"nabrajanje\">Ja, f\u00fcr die gesamte TMH-Serie sind passende pneumatische oder manuelle Fahrwerke erh\u00e4ltlich. Aufgrund des Eigengewichts des Ger\u00e4ts und der Last werden sie meist mit pneumatischen Fahrwerken geliefert, die mit integrierten Bremsen f\u00fcr das Fahren auf dem Tr\u00e4ger ausgestattet sind.<\/div>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/details>\n\t\t\t\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t<div class=\"elementor-element elementor-element-6b8738b e-con-full e-flex e-con e-child\" data-id=\"6b8738b\" data-element_type=\"container\" data-e-type=\"container\">\n\t\t<div class=\"elementor-element elementor-element-2c6325a e-con-full e-flex e-con e-child\" data-id=\"2c6325a\" data-element_type=\"container\" data-e-type=\"container\">\n\t\t\t\t<div class=\"elementor-element elementor-element-e15ea21 elementor-widget__width-inherit elementor-widget elementor-widget-heading\" data-id=\"e15ea21\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<div class=\"elementor-heading-title elementor-size-default\"><a href=\"https:\/\/dizalica.hr\/de\/pneumatische-hebezeuge\/\">PNEUMATISCHE HEBEZEUGE<\/a><\/div>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-e093376 elementor-widget-divider--view-line elementor-widget elementor-widget-divider\" data-id=\"e093376\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"divider.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<div class=\"elementor-divider\">\n\t\t\t<span class=\"elementor-divider-separator\">\n\t\t\t\t\t\t<\/span>\n\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-f29a84e elementor-widget__width-inherit elementor-widget elementor-widget-heading\" data-id=\"f29a84e\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<div class=\"elementor-heading-title elementor-size-default\"><a href=\"https:\/\/dizalica.hr\/de\/pneumatische-hebezeuge\/pneumatische-manipulatoren\/\">Pneumatische Manipulatoren<\/a><\/div>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-58b280a elementor-widget__width-inherit elementor-widget elementor-widget-heading\" data-id=\"58b280a\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<div class=\"elementor-heading-title elementor-size-default\"><a href=\"https:\/\/dizalica.hr\/de\/pneumatische-hebezeuge\/leichte-pneumatische-hebezeuge\/\">Leichte pneumatische Hebezeuge<\/a><\/div>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-e1dbadf elementor-widget__width-inherit elementor-widget elementor-widget-heading\" data-id=\"e1dbadf\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<div class=\"elementor-heading-title elementor-size-default\"><a href=\"https:\/\/dizalica.hr\/de\/pneumatische-hebezeuge\/professionelle-pneumatische-hebezeuge\/\">Industrielle pneumatische Hebeger\u00e4te<\/a><\/div>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-f0d1a9c elementor-widget__width-inherit elementor-widget elementor-widget-heading\" data-id=\"f0d1a9c\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<div class=\"elementor-heading-title elementor-size-default\"><a href=\"https:\/\/dizalica.hr\/de\/pneumatische-hebezeuge\/pneumatische-schnellhebezeuge\/\">Schnelle pneumatische Hubger\u00e4te<\/a><\/div>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-1913b4e elementor-widget__width-inherit elementor-widget elementor-widget-heading\" data-id=\"1913b4e\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<div class=\"elementor-heading-title elementor-size-default\">Pneumatische Hebezeuge f\u00fcr schwerste Lasten<\/div>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-486124b elementor-widget-divider--view-line elementor-widget elementor-widget-divider\" data-id=\"486124b\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"divider.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<div class=\"elementor-divider\">\n\t\t\t<span class=\"elementor-divider-separator\">\n\t\t\t\t\t\t<\/span>\n\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-bb48f90 elementor-widget__width-inherit elementor-widget elementor-widget-heading\" data-id=\"bb48f90\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<div class=\"elementor-heading-title elementor-size-default\"><a href=\"https:\/\/dizalica.hr\/de\/hebezeuge\/\">Hand- und Elektroseilz\u00fcge<\/a><\/div>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t<div class=\"elementor-element elementor-element-9be67a6 e-con-full e-flex e-con e-child\" data-id=\"9be67a6\" data-element_type=\"container\" data-e-type=\"container\">\n\t\t\t\t<div class=\"elementor-element elementor-element-617f00b elementor-widget elementor-widget-spacer\" data-id=\"617f00b\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"spacer.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<div class=\"elementor-spacer\">\n\t\t\t<div class=\"elementor-spacer-inner\"><\/div>\n\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-937246e link1 elementor-widget elementor-widget-heading\" data-id=\"937246e\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<div class=\"elementor-heading-title elementor-size-default\"><a href=\"https:\/\/dizalica.hr\/de\/blog\/\">Aus dem Blog<\/a><\/div>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-d8959a0 elementor-widget elementor-widget-etheme_posts_carousel\" data-id=\"d8959a0\" data-element_type=\"widget\" data-e-type=\"widget\" data-settings=\"{&quot;slides_per_view&quot;:&quot;1&quot;,&quot;slides_per_group&quot;:&quot;1&quot;,&quot;autoplay&quot;:&quot;yes&quot;,&quot;space_between&quot;:{&quot;unit&quot;:&quot;px&quot;,&quot;size&quot;:20,&quot;sizes&quot;:[]},&quot;space_between_tablet&quot;:{&quot;unit&quot;:&quot;px&quot;,&quot;size&quot;:&quot;&quot;,&quot;sizes&quot;:[]},&quot;space_between_mobile&quot;:{&quot;unit&quot;:&quot;px&quot;,&quot;size&quot;:&quot;&quot;,&quot;sizes&quot;:[]},&quot;loop&quot;:&quot;yes&quot;,&quot;autoplay_speed&quot;:5000,&quot;pause_on_hover&quot;:&quot;yes&quot;,&quot;pause_on_interaction&quot;:&quot;yes&quot;,&quot;navigation&quot;:&quot;arrows&quot;}\" data-widget_type=\"etheme_posts_carousel.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t            <div class=\"etheme-elementor-swiper-entry swiper-entry middle-inbox arrows-hover\">\n                \n                <div class=\"swiper etheme-elementor-slider swiper-container-main\" dir=\"ltr\">\n            \n                    <div class=\"swiper-wrapper\">\n                        \n                                                            <div class=\"swiper-slide\">\n                                        \t\t<article class=\"etheme-post post-44531 post type-post status-publish format-standard has-post-thumbnail hentry category-blog category-savjeti\">\n\t\t            <div class=\"etheme-post-image-wrapper etheme-image-hover etheme-image-hover-scaleIn\">\n                <a class=\"etheme-post-image-inner\" href=\"https:\/\/dizalica.hr\/de\/die-haufigsten-fehler-bei-der-lagerung-von-paletten-und-wie-sie-diese-vermeiden\/\">\n                    <img loading=\"lazy\" loading=\"lazy\" decoding=\"async\" width=\"300\" height=\"200\" src=\"https:\/\/dizalica.hr\/wp-content\/uploads\/xstore\/xstore-placeholder-300x300.png\" class=\"attachment-medium size-medium wp-image-44867 lazyload lazyload-simple et-lazyload-fadeIn\" alt=\"Elektro-Hubwagen f\u00fcr Lager und Palettentransport\" sizes=\"auto, (max-width: 300px) 100vw, 300px\" data-src=\"https:\/\/dizalica.hr\/wp-content\/uploads\/2026\/07\/skladistenje-paleta-300x200.avif\" data-srcset=\"https:\/\/dizalica.hr\/wp-content\/uploads\/2026\/07\/skladistenje-paleta-300x200.avif 300w, https:\/\/dizalica.hr\/wp-content\/uploads\/2026\/07\/skladistenje-paleta-1024x683.avif 1024w, https:\/\/dizalica.hr\/wp-content\/uploads\/2026\/07\/skladistenje-paleta-768x512.avif 768w, https:\/\/dizalica.hr\/wp-content\/uploads\/2026\/07\/skladistenje-paleta-600x400.avif 600w, https:\/\/dizalica.hr\/wp-content\/uploads\/2026\/07\/skladistenje-paleta-1x1.avif 1w, https:\/\/dizalica.hr\/wp-content\/uploads\/2026\/07\/skladistenje-paleta-10x7.avif 10w, https:\/\/dizalica.hr\/wp-content\/uploads\/2026\/07\/skladistenje-paleta.avif 1200w\" \/>                <\/a>\n                            <\/div>\n                        <div class=\"etheme-post-content \">\n\t\t\t\t<div class=\"etheme-post-title\"><a href=\"https:\/\/dizalica.hr\/de\/die-haufigsten-fehler-bei-der-lagerung-von-paletten-und-wie-sie-diese-vermeiden\/\">Die h\u00e4ufigsten Fehler bei der Lagerung von Paletten und wie Sie diese vermeiden<\/a><\/div><a class=\"etheme-post-button\" href=\"https:\/\/dizalica.hr\/de\/die-haufigsten-fehler-bei-der-lagerung-von-paletten-und-wie-sie-diese-vermeiden\/\"><span class=\"button-text\">Mehr<\/span><svg xmlns=\"http:\/\/www.w3.org\/2000\/svg\" width=\"1em\" height=\"1em\" viewBox=\"0 0 24 24\" fill=\"currentColor\"><path d=\"M23.928 11.832c-0.048-0.12-0.12-0.216-0.168-0.264l-7.776-8.16c-0.12-0.144-0.288-0.216-0.48-0.24-0.168 0-0.36 0.048-0.48 0.168-0.288 0.24-0.312 0.672-0.048 0.984l6.648 6.984h-20.904c-0.384 0-0.696 0.312-0.696 0.696s0.312 0.672 0.696 0.672h20.904l-6.624 7.008c-0.12 0.144-0.192 0.312-0.168 0.48 0 0.192 0.096 0.36 0.216 0.48 0.12 0.144 0.312 0.216 0.48 0.216 0.144 0 0.312-0.048 0.48-0.192l7.776-8.16c0 0 0.168-0.264 0.168-0.336 0.024-0.12 0.024-0.216-0.024-0.336z\"><\/path><\/svg><\/a>            <\/div>\n\t\t\t\t<\/article>\n\t\t                                    <\/div>\n                                                                    <div class=\"swiper-slide\">\n                                        \t\t<article class=\"etheme-post post-37111 post type-post status-publish format-standard has-post-thumbnail hentry category-vodici-za-odabir tag-montaza tag-proizvodni-pogoni tag-servis tag-skladiste-i-logistika\">\n\t\t            <div class=\"etheme-post-image-wrapper etheme-image-hover etheme-image-hover-scaleIn\">\n                <a class=\"etheme-post-image-inner\" href=\"https:\/\/dizalica.hr\/de\/wie-wahlen-sie-den-richtigen-hebekran-fur-ihr-unternehmen-aus-leitfaden-fur-industrielle-hebezeuge-und-kransysteme\/\">\n                    <img loading=\"lazy\" loading=\"lazy\" decoding=\"async\" width=\"300\" height=\"158\" src=\"https:\/\/dizalica.hr\/wp-content\/uploads\/elementor\/thumbs\/xstore-placeholder-rhc8czj3f7x9oet9rtvahaogu6r2b5wufdtc58uu08.png\" class=\"attachment-medium size-medium wp-image-38130 lazyload lazyload-simple et-lazyload-fadeIn\" alt=\"Elektrische Hubwagen f\u00fcr das Lager \u2013 Leitfaden zur Auswahl von Industrieausr\u00fcstung\" sizes=\"auto, (max-width: 300px) 100vw, 300px\" data-src=\"https:\/\/dizalica.hr\/wp-content\/uploads\/2026\/02\/kako-odabrati-industrijsku-dizalicu-300x158.avif\" data-srcset=\"https:\/\/dizalica.hr\/wp-content\/uploads\/2026\/02\/kako-odabrati-industrijsku-dizalicu-300x158.avif 300w, https:\/\/dizalica.hr\/wp-content\/uploads\/2026\/02\/kako-odabrati-industrijsku-dizalicu-1024x538.avif 1024w, https:\/\/dizalica.hr\/wp-content\/uploads\/2026\/02\/kako-odabrati-industrijsku-dizalicu-768x403.avif 768w, https:\/\/dizalica.hr\/wp-content\/uploads\/2026\/02\/kako-odabrati-industrijsku-dizalicu-600x315.avif 600w, https:\/\/dizalica.hr\/wp-content\/uploads\/2026\/02\/kako-odabrati-industrijsku-dizalicu-1x1.avif 1w, https:\/\/dizalica.hr\/wp-content\/uploads\/2026\/02\/kako-odabrati-industrijsku-dizalicu-10x5.avif 10w, https:\/\/dizalica.hr\/wp-content\/uploads\/2026\/02\/kako-odabrati-industrijsku-dizalicu.avif 1200w\" \/>                <\/a>\n                            <\/div>\n                        <div class=\"etheme-post-content \">\n\t\t\t\t<div class=\"etheme-post-title\"><a href=\"https:\/\/dizalica.hr\/de\/wie-wahlen-sie-den-richtigen-hebekran-fur-ihr-unternehmen-aus-leitfaden-fur-industrielle-hebezeuge-und-kransysteme\/\">Wie w\u00e4hlen Sie den richtigen Hebekran f\u00fcr Ihr Unternehmen aus? Leitfaden f\u00fcr industrielle Hebezeuge und Kransysteme<\/a><\/div><a class=\"etheme-post-button\" href=\"https:\/\/dizalica.hr\/de\/wie-wahlen-sie-den-richtigen-hebekran-fur-ihr-unternehmen-aus-leitfaden-fur-industrielle-hebezeuge-und-kransysteme\/\"><span class=\"button-text\">Mehr<\/span><svg xmlns=\"http:\/\/www.w3.org\/2000\/svg\" width=\"1em\" height=\"1em\" viewBox=\"0 0 24 24\" fill=\"currentColor\"><path d=\"M23.928 11.832c-0.048-0.12-0.12-0.216-0.168-0.264l-7.776-8.16c-0.12-0.144-0.288-0.216-0.48-0.24-0.168 0-0.36 0.048-0.48 0.168-0.288 0.24-0.312 0.672-0.048 0.984l6.648 6.984h-20.904c-0.384 0-0.696 0.312-0.696 0.696s0.312 0.672 0.696 0.672h20.904l-6.624 7.008c-0.12 0.144-0.192 0.312-0.168 0.48 0 0.192 0.096 0.36 0.216 0.48 0.12 0.144 0.312 0.216 0.48 0.216 0.144 0 0.312-0.048 0.48-0.192l7.776-8.16c0 0 0.168-0.264 0.168-0.336 0.024-0.12 0.024-0.216-0.024-0.336z\"><\/path><\/svg><\/a>            <\/div>\n\t\t\t\t<\/article>\n\t\t                                    <\/div>\n                                                                    <div class=\"swiper-slide\">\n                                        \t\t<article class=\"etheme-post post-37401 post type-post status-publish format-standard has-post-thumbnail hentry category-savjeti tag-gradevina tag-montaza tag-servis tag-transport\">\n\t\t            <div class=\"etheme-post-image-wrapper etheme-image-hover etheme-image-hover-scaleIn\">\n                <a class=\"etheme-post-image-inner\" href=\"https:\/\/dizalica.hr\/de\/wie-sie-eine-kettenratsche-richtig-verwenden-schritt-fuer-schritt-anleitung\/\">\n                    <img loading=\"lazy\" loading=\"lazy\" decoding=\"async\" width=\"300\" height=\"158\" src=\"https:\/\/dizalica.hr\/wp-content\/uploads\/elementor\/thumbs\/xstore-placeholder-rhc8czj3f7x9oet9rtvahaogu6r2b5wufdtc58uu08.png\" class=\"attachment-medium size-medium wp-image-38030 lazyload lazyload-simple et-lazyload-fadeIn\" alt=\"RLSHK 13mm Kettenzurrger\u00e4t f\u00fcr schwere Ausr\u00fcstung und Ladungssicherung\" sizes=\"auto, (max-width: 300px) 100vw, 300px\" data-src=\"https:\/\/dizalica.hr\/wp-content\/uploads\/2026\/02\/lancani-zatezac-rlshk-13mm-primjena-teska-oprema-02-300x158.avif\" data-srcset=\"https:\/\/dizalica.hr\/wp-content\/uploads\/2026\/02\/lancani-zatezac-rlshk-13mm-primjena-teska-oprema-02-300x158.avif 300w, https:\/\/dizalica.hr\/wp-content\/uploads\/2026\/02\/lancani-zatezac-rlshk-13mm-primjena-teska-oprema-02-1024x538.avif 1024w, https:\/\/dizalica.hr\/wp-content\/uploads\/2026\/02\/lancani-zatezac-rlshk-13mm-primjena-teska-oprema-02-768x403.avif 768w, https:\/\/dizalica.hr\/wp-content\/uploads\/2026\/02\/lancani-zatezac-rlshk-13mm-primjena-teska-oprema-02-600x315.avif 600w, https:\/\/dizalica.hr\/wp-content\/uploads\/2026\/02\/lancani-zatezac-rlshk-13mm-primjena-teska-oprema-02-1x1.avif 1w, https:\/\/dizalica.hr\/wp-content\/uploads\/2026\/02\/lancani-zatezac-rlshk-13mm-primjena-teska-oprema-02-10x5.avif 10w, https:\/\/dizalica.hr\/wp-content\/uploads\/2026\/02\/lancani-zatezac-rlshk-13mm-primjena-teska-oprema-02.avif 1200w\" \/>                <\/a>\n                            <\/div>\n                        <div class=\"etheme-post-content \">\n\t\t\t\t<div class=\"etheme-post-title\"><a href=\"https:\/\/dizalica.hr\/de\/wie-sie-eine-kettenratsche-richtig-verwenden-schritt-fuer-schritt-anleitung\/\">Wie Sie eine Kettenratsche richtig verwenden \u2013 Schritt-f\u00fcr-Schritt-Anleitung<\/a><\/div><a class=\"etheme-post-button\" href=\"https:\/\/dizalica.hr\/de\/wie-sie-eine-kettenratsche-richtig-verwenden-schritt-fuer-schritt-anleitung\/\"><span class=\"button-text\">Mehr<\/span><svg xmlns=\"http:\/\/www.w3.org\/2000\/svg\" width=\"1em\" height=\"1em\" viewBox=\"0 0 24 24\" fill=\"currentColor\"><path d=\"M23.928 11.832c-0.048-0.12-0.12-0.216-0.168-0.264l-7.776-8.16c-0.12-0.144-0.288-0.216-0.48-0.24-0.168 0-0.36 0.048-0.48 0.168-0.288 0.24-0.312 0.672-0.048 0.984l6.648 6.984h-20.904c-0.384 0-0.696 0.312-0.696 0.696s0.312 0.672 0.696 0.672h20.904l-6.624 7.008c-0.12 0.144-0.192 0.312-0.168 0.48 0 0.192 0.096 0.36 0.216 0.48 0.12 0.144 0.312 0.216 0.48 0.216 0.144 0 0.312-0.048 0.48-0.192l7.776-8.16c0 0 0.168-0.264 0.168-0.336 0.024-0.12 0.024-0.216-0.024-0.336z\"><\/path><\/svg><\/a>            <\/div>\n\t\t\t\t<\/article>\n\t\t                                    <\/div>\n                                                                    <div class=\"swiper-slide\">\n                                        \t\t<article class=\"etheme-post post-37402 post type-post status-publish format-standard has-post-thumbnail hentry category-kaufberater category-blog category-vodici-za-odabir tag-skladiste-i-logistika tag-transport tag-trgovina\">\n\t\t            <div class=\"etheme-post-image-wrapper etheme-image-hover etheme-image-hover-scaleIn\">\n                <a class=\"etheme-post-image-inner\" href=\"https:\/\/dizalica.hr\/de\/wie-sie-den-richtigen-elektrischen-palettenheber-fuer-ihre-anforderungen-auswaehlen-interaktiver-test\/\">\n                    <img loading=\"lazy\" loading=\"lazy\" decoding=\"async\" width=\"300\" height=\"158\" src=\"https:\/\/dizalica.hr\/wp-content\/uploads\/elementor\/thumbs\/xstore-placeholder-rhc8czj3f7x9oet9rtvahaogu6r2b5wufdtc58uu08.png\" class=\"attachment-medium size-medium wp-image-26099 lazyload lazyload-simple et-lazyload-fadeIn\" alt=\"Kako odabrati elektri\u010dni paletar\" sizes=\"auto, (max-width: 300px) 100vw, 300px\" data-src=\"https:\/\/dizalica.hr\/wp-content\/uploads\/2026\/01\/kako-odabrati-elektricni-paletar-300x158.avif\" data-srcset=\"https:\/\/dizalica.hr\/wp-content\/uploads\/2026\/01\/kako-odabrati-elektricni-paletar-300x158.avif 300w, https:\/\/dizalica.hr\/wp-content\/uploads\/2026\/01\/kako-odabrati-elektricni-paletar-1024x538.avif 1024w, https:\/\/dizalica.hr\/wp-content\/uploads\/2026\/01\/kako-odabrati-elektricni-paletar-768x403.avif 768w, https:\/\/dizalica.hr\/wp-content\/uploads\/2026\/01\/kako-odabrati-elektricni-paletar-600x315.avif 600w, https:\/\/dizalica.hr\/wp-content\/uploads\/2026\/01\/kako-odabrati-elektricni-paletar-1x1.avif 1w, https:\/\/dizalica.hr\/wp-content\/uploads\/2026\/01\/kako-odabrati-elektricni-paletar-10x5.avif 10w, https:\/\/dizalica.hr\/wp-content\/uploads\/2026\/01\/kako-odabrati-elektricni-paletar.avif 1200w\" \/>                <\/a>\n                            <\/div>\n                        <div class=\"etheme-post-content \">\n\t\t\t\t<div class=\"etheme-post-title\"><a href=\"https:\/\/dizalica.hr\/de\/wie-sie-den-richtigen-elektrischen-palettenheber-fuer-ihre-anforderungen-auswaehlen-interaktiver-test\/\">Wie w\u00e4hlt man den richtigen elektrischen Palettenhubwagen aus?<\/a><\/div><a class=\"etheme-post-button\" href=\"https:\/\/dizalica.hr\/de\/wie-sie-den-richtigen-elektrischen-palettenheber-fuer-ihre-anforderungen-auswaehlen-interaktiver-test\/\"><span class=\"button-text\">Mehr<\/span><svg xmlns=\"http:\/\/www.w3.org\/2000\/svg\" width=\"1em\" height=\"1em\" viewBox=\"0 0 24 24\" fill=\"currentColor\"><path d=\"M23.928 11.832c-0.048-0.12-0.12-0.216-0.168-0.264l-7.776-8.16c-0.12-0.144-0.288-0.216-0.48-0.24-0.168 0-0.36 0.048-0.48 0.168-0.288 0.24-0.312 0.672-0.048 0.984l6.648 6.984h-20.904c-0.384 0-0.696 0.312-0.696 0.696s0.312 0.672 0.696 0.672h20.904l-6.624 7.008c-0.12 0.144-0.192 0.312-0.168 0.48 0 0.192 0.096 0.36 0.216 0.48 0.12 0.144 0.312 0.216 0.48 0.216 0.144 0 0.312-0.048 0.48-0.192l7.776-8.16c0 0 0.168-0.264 0.168-0.336 0.024-0.12 0.024-0.216-0.024-0.336z\"><\/path><\/svg><\/a>            <\/div>\n\t\t\t\t<\/article>\n\t\t                                    <\/div>\n                                                        \n                    <\/div>\n\t\n\t                \t\t<div class=\"swiper-button-prev swiper-custom-left et-swiper-elementor-nav type-arrow style-4\"><\/div>\n\t\t<div class=\"swiper-button-next swiper-custom-right et-swiper-elementor-nav type-arrow style-4\"><\/div>\n\t\t                 \n                <\/div>\n\t\n\t                         \n            <\/div>\n\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t<div class=\"elementor-element elementor-element-7bb6d34 e-con-full e-flex e-con e-child\" data-id=\"7bb6d34\" data-element_type=\"container\" data-e-type=\"container\">\n\t\t\t\t<div class=\"elementor-element elementor-element-a73a5e5 link1 elementor-widget elementor-widget-global elementor-global-12498 elementor-widget-heading\" data-id=\"a73a5e5\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<div class=\"elementor-heading-title elementor-size-default\"><a href=\"https:\/\/dizalica.hr\/de\/aktionen\/\">Akcijska ponuda<\/a><\/div>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-02fa2d2 eael-product-grid-column-1 elementor-widget elementor-widget-global elementor-global-12501 elementor-widget-eicon-woocommerce\" data-id=\"02fa2d2\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"eicon-woocommerce.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\n        <div class=\"eael-product-grid eael-product-reveal grid\" id=\"eael-product-grid\" data-widget-id=\"02fa2d2\" data-page-id=\"42276\" data-nonce=\"a7a6d18826\" >\n            <div class=\"woocommerce\">\n                <ul class=\"products eael-post-appender eael-post-appender-02fa2d2\" data-ssi-desktop=\"no\" data-ssi-tablet=\"\" data-ssi-mobile=\"\" data-layout-mode=\"grid\"> <li class=\"product \">\n<div class=\"eael-product-wrap\" data-src=\"\" data-src-hover=\"\">\n    <a href=\"https:\/\/dizalica.hr\/de\/hydraulische-hubtische\/einfachscheren-elektrisch\/hydraulischer-elektrischer-hebetisch-2t\/\" class=\"woocommerce-LoopProduct-link woocommerce-loop-product__link\"><img decoding=\"async\" width=\"150\" height=\"150\" src=\"https:\/\/dizalica.hr\/wp-content\/uploads\/xstore\/xstore-placeholder-1x1.png\" class=\"attachment-woocommerce_thumbnail size-woocommerce_thumbnail wvs-archive-product-image lazyload lazyload-simple et-lazyload-fadeIn\" alt=\"Elektrisch betriebene Scherenhubtisch, Tragf\u00e4higkeit 2000 kg, f\u00fcr Lager und Industrie\" loading=\"eager\" sizes=\"(max-width: 150px) 100vw, 150px\" data-src=\"https:\/\/dizalica.hr\/wp-content\/uploads\/2024\/08\/jednoskarasti-hidraulicni-stol-HW_-150x150.avif\" data-srcset=\"https:\/\/dizalica.hr\/wp-content\/uploads\/2024\/08\/jednoskarasti-hidraulicni-stol-HW_-150x150.avif 150w, https:\/\/dizalica.hr\/wp-content\/uploads\/2024\/08\/jednoskarasti-hidraulicni-stol-HW_-300x300.avif 300w, https:\/\/dizalica.hr\/wp-content\/uploads\/2024\/08\/jednoskarasti-hidraulicni-stol-HW_-12x12.avif 12w, https:\/\/dizalica.hr\/wp-content\/uploads\/2024\/08\/jednoskarasti-hidraulicni-stol-HW_-100x100.avif 100w, https:\/\/dizalica.hr\/wp-content\/uploads\/2024\/08\/jednoskarasti-hidraulicni-stol-HW_-1x1.avif 1w, https:\/\/dizalica.hr\/wp-content\/uploads\/2024\/08\/jednoskarasti-hidraulicni-stol-HW_-10x10.avif 10w, https:\/\/dizalica.hr\/wp-content\/uploads\/2024\/08\/jednoskarasti-hidraulicni-stol-HW_.avif 600w\" \/><\/a><div class=\"eael-product-title\">\n    <a href=\"https:\/\/dizalica.hr\/de\/hydraulische-hubtische\/einfachscheren-elektrisch\/hydraulischer-elektrischer-hebetisch-2t\/\" class=\"woocommerce-LoopProduct-link woocommerce-loop-product__link\"><span class=\"woocommerce-loop-product__title\">Hydraulischer elektrischer Hebetisch 2t<\/span><\/a>\n    <\/div><div class=\"eael-star-rating star-rating\"><span style=\"width:0%\">Bewertet mit <strong class=\"rating\">0<\/strong> von 5<\/span><\/div><span class=\"onsale sale-preset-5 \">Akcija<\/span><div class=\"eael-product-price\"><span class=\"dizalica-vpc-price\">Netto: <del><span class=\"woocommerce-Price-amount amount\"><bdi>1.220,00&nbsp;<span class=\"woocommerce-Price-currencySymbol\" translate=\"no\">&euro;<\/span><\/bdi><\/span> \u2013 <span class=\"woocommerce-Price-amount amount\"><bdi>2.460,00&nbsp;<span class=\"woocommerce-Price-currencySymbol\" translate=\"no\">&euro;<\/span><\/bdi><\/span><\/del> <ins><span class=\"woocommerce-Price-amount amount\"><bdi>1.159,00&nbsp;<span class=\"woocommerce-Price-currencySymbol\" translate=\"no\">&euro;<\/span><\/bdi><\/span> \u2013 <span class=\"woocommerce-Price-amount amount\"><bdi>2.460,00&nbsp;<span class=\"woocommerce-Price-currencySymbol\" translate=\"no\">&euro;<\/span><\/bdi><\/span><\/ins><\/span><br><span class=\"dizalica-mpc-price\" style=\"font-size:80%;\">Brutto: <del><span class=\"woocommerce-Price-amount amount\"><bdi>1.525,00&nbsp;<span class=\"woocommerce-Price-currencySymbol\" translate=\"no\">&euro;<\/span><\/bdi><\/span> \u2013 <span class=\"woocommerce-Price-amount amount\"><bdi>3.075,00&nbsp;<span class=\"woocommerce-Price-currencySymbol\" translate=\"no\">&euro;<\/span><\/bdi><\/span><\/del> <ins><span class=\"woocommerce-Price-amount amount\"><bdi>1.448,75&nbsp;<span class=\"woocommerce-Price-currencySymbol\" translate=\"no\">&euro;<\/span><\/bdi><\/span> \u2013 <span class=\"woocommerce-Price-amount amount\"><bdi>3.075,00&nbsp;<span class=\"woocommerce-Price-currencySymbol\" translate=\"no\">&euro;<\/span><\/bdi><\/span><\/ins><\/span><\/div>    <a href=\"https:\/\/dizalica.hr\/de\/hydraulische-hubtische\/einfachscheren-elektrisch\/hydraulischer-elektrischer-hebetisch-2t\/\" aria-describedby=\"woocommerce_loop_add_to_cart_link_describedby_36371\" data-quantity=\"1\" class=\"button product_type_variable add_to_cart_button\" data-product_id=\"36371\" data-product_sku=\"\" aria-label=\"W\u00e4hle Optionen f\u00fcr \u201eHydraulischer elektrischer Hebetisch 2t\u201c\" rel=\"nofollow\" data-product_name=\"Hydraulischer elektrischer Hebetisch 2t\">Odaberite opcije<\/a>\t<span id=\"woocommerce_loop_add_to_cart_link_describedby_36371\" class=\"screen-reader-text\">\n\t\tDieses Produkt weist mehrere Varianten auf. Die Optionen k\u00f6nnen auf der Produktseite gew\u00e4hlt werden\t<\/span>\n    \n<\/div>\n\n<\/li><\/ul>            <div class=\"eael-load-more-button-wrap eael-force-hide\">\n                <button class=\"eael-load-more-button\" id=\"eael-load-more-btn-02fa2d2\" data-widget-id=\"02fa2d2\" data-widget=\"02fa2d2\" data-page-id=\"42276\" data-template=\"{&quot;dir&quot;:&quot;lite&quot;,&quot;file_name&quot;:&quot;reveal.php&quot;,&quot;name&quot;:&quot;Eicon-Woocommerce&quot;}\" data-class=\"Essential_Addons_Elementor\\Elements\\Product_Grid\" data-layout=\"grid\" data-page=\"1\" data-args=\"post_type=product&amp;post_status%5B0%5D=publish&amp;posts_per_page=1&amp;order=desc&amp;offset=0&amp;tax_query%5Brelation%5D=AND&amp;tax_query%5B0%5D%5Btaxonomy%5D=product_visibility&amp;tax_query%5B0%5D%5Bfield%5D=name&amp;tax_query%5B0%5D%5Bterms%5D%5B0%5D=exclude-from-search&amp;tax_query%5B0%5D%5Bterms%5D%5B1%5D=exclude-from-catalog&amp;tax_query%5B0%5D%5Boperator%5D=NOT+IN&amp;meta_query%5Brelation%5D=AND&amp;meta_query%5B0%5D%5Bkey%5D=_stock_status&amp;meta_query%5B0%5D%5Bvalue%5D=instock&amp;orderby=rand&amp;post__in%5B0%5D=0&amp;post__in%5B1%5D=2340&amp;post__in%5B2%5D=2341&amp;post__in%5B3%5D=2342&amp;post__in%5B4%5D=2343&amp;post__in%5B5%5D=2344&amp;post__in%5B6%5D=2345&amp;post__in%5B7%5D=2346&amp;post__in%5B8%5D=2404&amp;post__in%5B9%5D=2405&amp;post__in%5B10%5D=2406&amp;post__in%5B11%5D=2407&amp;post__in%5B12%5D=2408&amp;post__in%5B13%5D=2409&amp;post__in%5B14%5D=2410&amp;post__in%5B15%5D=2490&amp;post__in%5B16%5D=2949&amp;post__in%5B17%5D=2950&amp;post__in%5B18%5D=2951&amp;post__in%5B19%5D=2952&amp;post__in%5B20%5D=2953&amp;post__in%5B21%5D=2954&amp;post__in%5B22%5D=2955&amp;post__in%5B23%5D=2956&amp;post__in%5B24%5D=2957&amp;post__in%5B25%5D=2958&amp;post__in%5B26%5D=2959&amp;post__in%5B27%5D=2960&amp;post__in%5B28%5D=2961&amp;post__in%5B29%5D=2962&amp;post__in%5B30%5D=2963&amp;post__in%5B31%5D=2964&amp;post__in%5B32%5D=2965&amp;post__in%5B33%5D=2966&amp;post__in%5B34%5D=2967&amp;post__in%5B35%5D=2968&amp;post__in%5B36%5D=2969&amp;post__in%5B37%5D=2970&amp;post__in%5B38%5D=2971&amp;post__in%5B39%5D=2972&amp;post__in%5B40%5D=2973&amp;post__in%5B41%5D=2974&amp;post__in%5B42%5D=2975&amp;post__in%5B43%5D=2976&amp;post__in%5B44%5D=2977&amp;post__in%5B45%5D=2978&amp;post__in%5B46%5D=2979&amp;post__in%5B47%5D=2980&amp;post__in%5B48%5D=2981&amp;post__in%5B49%5D=2982&amp;post__in%5B50%5D=2983&amp;post__in%5B51%5D=3565&amp;post__in%5B52%5D=3566&amp;post__in%5B53%5D=3567&amp;post__in%5B54%5D=3568&amp;post__in%5B55%5D=3569&amp;post__in%5B56%5D=3570&amp;post__in%5B57%5D=3571&amp;post__in%5B58%5D=3572&amp;post__in%5B59%5D=3744&amp;post__in%5B60%5D=3839&amp;post__in%5B61%5D=3848&amp;post__in%5B62%5D=3923&amp;post__in%5B63%5D=3943&amp;post__in%5B64%5D=3946&amp;post__in%5B65%5D=3948&amp;post__in%5B66%5D=3952&amp;post__in%5B67%5D=3980&amp;post__in%5B68%5D=4018&amp;post__in%5B69%5D=5911&amp;post__in%5B70%5D=5974&amp;post__in%5B71%5D=5975&amp;post__in%5B72%5D=5977&amp;post__in%5B73%5D=6024&amp;post__in%5B74%5D=6025&amp;post__in%5B75%5D=30318&amp;post__in%5B76%5D=32268&amp;post__in%5B77%5D=32269&amp;post__in%5B78%5D=32270&amp;post__in%5B79%5D=32271&amp;post__in%5B80%5D=32272&amp;post__in%5B81%5D=32969&amp;post__in%5B82%5D=32970&amp;post__in%5B83%5D=32971&amp;post__in%5B84%5D=32972&amp;post__in%5B85%5D=32973&amp;post__in%5B86%5D=32974&amp;post__in%5B87%5D=32975&amp;post__in%5B88%5D=32984&amp;post__in%5B89%5D=32985&amp;post__in%5B90%5D=32986&amp;post__in%5B91%5D=32987&amp;post__in%5B92%5D=32988&amp;post__in%5B93%5D=32989&amp;post__in%5B94%5D=32990&amp;post__in%5B95%5D=33692&amp;post__in%5B96%5D=33693&amp;post__in%5B97%5D=33694&amp;post__in%5B98%5D=33695&amp;post__in%5B99%5D=33696&amp;post__in%5B100%5D=33697&amp;post__in%5B101%5D=33698&amp;post__in%5B102%5D=33936&amp;post__in%5B103%5D=33938&amp;post__in%5B104%5D=33961&amp;post__in%5B105%5D=33972&amp;post__in%5B106%5D=34066&amp;post__in%5B107%5D=34070&amp;post__in%5B108%5D=34115&amp;post__in%5B109%5D=34243&amp;post__in%5B110%5D=34282&amp;post__in%5B111%5D=34297&amp;post__in%5B112%5D=35270&amp;post__in%5B113%5D=35271&amp;post__in%5B114%5D=35272&amp;post__in%5B115%5D=35273&amp;post__in%5B116%5D=35274&amp;post__in%5B117%5D=35380&amp;post__in%5B118%5D=35381&amp;post__in%5B119%5D=35382&amp;post__in%5B120%5D=35383&amp;post__in%5B121%5D=35384&amp;post__in%5B122%5D=35385&amp;post__in%5B123%5D=35386&amp;post__in%5B124%5D=35387&amp;post__in%5B125%5D=35388&amp;post__in%5B126%5D=35389&amp;post__in%5B127%5D=35390&amp;post__in%5B128%5D=35391&amp;post__in%5B129%5D=35392&amp;post__in%5B130%5D=35393&amp;post__in%5B131%5D=35394&amp;post__in%5B132%5D=35395&amp;post__in%5B133%5D=35396&amp;post__in%5B134%5D=35397&amp;post__in%5B135%5D=35398&amp;post__in%5B136%5D=35399&amp;post__in%5B137%5D=35400&amp;post__in%5B138%5D=35401&amp;post__in%5B139%5D=35402&amp;post__in%5B140%5D=35403&amp;post__in%5B141%5D=35404&amp;post__in%5B142%5D=35405&amp;post__in%5B143%5D=35406&amp;post__in%5B144%5D=35407&amp;post__in%5B145%5D=35408&amp;post__in%5B146%5D=35409&amp;post__in%5B147%5D=35410&amp;post__in%5B148%5D=35411&amp;post__in%5B149%5D=35412&amp;post__in%5B150%5D=35413&amp;post__in%5B151%5D=35414&amp;post__in%5B152%5D=36370&amp;post__in%5B153%5D=36487&amp;post__in%5B154%5D=36574&amp;post__in%5B155%5D=36576&amp;post__in%5B156%5D=36580&amp;post__in%5B157%5D=36581&amp;post__in%5B158%5D=36844&amp;post__in%5B159%5D=36864&amp;post__in%5B160%5D=37146&amp;post__in%5B161%5D=37147&amp;post__in%5B162%5D=37148&amp;post__in%5B163%5D=37149&amp;post__in%5B164%5D=37150&amp;post__in%5B165%5D=37163&amp;post__in%5B166%5D=37194&amp;post__in%5B167%5D=37745&amp;post__in%5B168%5D=39603&amp;post__in%5B169%5D=39604&amp;post__in%5B170%5D=39605&amp;post__in%5B171%5D=39606&amp;post__in%5B172%5D=39607&amp;post__in%5B173%5D=39608&amp;post__in%5B174%5D=39609&amp;post__in%5B175%5D=39610&amp;post__in%5B176%5D=39740&amp;post__in%5B177%5D=39741&amp;post__in%5B178%5D=39742&amp;post__in%5B179%5D=39743&amp;post__in%5B180%5D=39744&amp;post__in%5B181%5D=39745&amp;post__in%5B182%5D=39746&amp;post__in%5B183%5D=40102&amp;post__in%5B184%5D=40103&amp;post__in%5B185%5D=40105&amp;post__in%5B186%5D=40113&amp;post__in%5B187%5D=40114&amp;post__in%5B188%5D=40115&amp;post__in%5B189%5D=40116&amp;post__in%5B190%5D=40117&amp;post__in%5B191%5D=40118&amp;post__in%5B192%5D=40119&amp;post__in%5B193%5D=40120&amp;post__in%5B194%5D=40203&amp;post__in%5B195%5D=40204&amp;post__in%5B196%5D=40276&amp;post__in%5B197%5D=40277&amp;post__in%5B198%5D=40278&amp;post__in%5B199%5D=40279&amp;post__in%5B200%5D=40280&amp;post__in%5B201%5D=40282&amp;post__in%5B202%5D=40285&amp;post__in%5B203%5D=40287&amp;post__in%5B204%5D=40288&amp;post__in%5B205%5D=40290&amp;post__in%5B206%5D=40292&amp;post__in%5B207%5D=40294&amp;post__in%5B208%5D=40296&amp;post__in%5B209%5D=40298&amp;post__in%5B210%5D=40299&amp;post__in%5B211%5D=40302&amp;post__in%5B212%5D=40304&amp;post__in%5B213%5D=40305&amp;post__in%5B214%5D=40308&amp;post__in%5B215%5D=40309&amp;post__in%5B216%5D=40311&amp;post__in%5B217%5D=40313&amp;post__in%5B218%5D=40315&amp;post__in%5B219%5D=40317&amp;post__in%5B220%5D=40319&amp;post__in%5B221%5D=40321&amp;post__in%5B222%5D=40324&amp;post__in%5B223%5D=40327&amp;post__in%5B224%5D=40329&amp;post__in%5B225%5D=40330&amp;post__in%5B226%5D=40332&amp;post__in%5B227%5D=40335&amp;post__in%5B228%5D=40336&amp;post__in%5B229%5D=40338&amp;post__in%5B230%5D=40341&amp;post__in%5B231%5D=41075&amp;post__in%5B232%5D=41210&amp;post__in%5B233%5D=41226&amp;post__in%5B234%5D=41229&amp;post__in%5B235%5D=41230&amp;post__in%5B236%5D=41232&amp;post__in%5B237%5D=41330&amp;post__in%5B238%5D=41332&amp;post__in%5B239%5D=42296&amp;post__in%5B240%5D=43899&amp;post__in%5B241%5D=835&amp;post__in%5B242%5D=824&amp;post__in%5B243%5D=2948&amp;post__in%5B244%5D=3564&amp;post__in%5B245%5D=3743&amp;post__in%5B246%5D=3834&amp;post__in%5B247%5D=3843&amp;post__in%5B248%5D=3977&amp;post__in%5B249%5D=4015&amp;post__in%5B250%5D=5907&amp;post__in%5B251%5D=5973&amp;post__in%5B252%5D=6017&amp;post__in%5B253%5D=32219&amp;post__in%5B254%5D=32964&amp;post__in%5B255%5D=32979&amp;post__in%5B256%5D=33690&amp;post__in%5B257%5D=33934&amp;post__in%5B258%5D=34063&amp;post__in%5B259%5D=34293&amp;post__in%5B260%5D=35549&amp;post__in%5B261%5D=35379&amp;post__in%5B262%5D=36419&amp;post__in%5B263%5D=36418&amp;post__in%5B264%5D=37138&amp;post__in%5B265%5D=37156&amp;post__in%5B266%5D=37188&amp;post__in%5B267%5D=36426&amp;post__in%5B268%5D=36545&amp;post__in%5B269%5D=36371&amp;post__in%5B270%5D=36415&amp;post__in%5B271%5D=37481&amp;post__in%5B272%5D=37767&amp;post__in%5B273%5D=36459&amp;post__in%5B274%5D=36424&amp;post__in%5B275%5D=36431&amp;post__in%5B276%5D=36376&amp;post__in%5B277%5D=36384&amp;post__in%5B278%5D=36466&amp;post__in%5B279%5D=37409&amp;total_post=20\" data-max-page=\"20\">\n                    <span class=\"eael-btn-loader button__loader\"><\/span>\n                    <span class=\"eael_load_more_text\"><\/span>\n                <\/button>\n            <\/div>\n                        <\/div>\n        <\/div>\n\n        <script type=\"text\/javascript\">\n            jQuery(document).ready(function($) {\n                var $scope = jQuery(\".elementor-element-02fa2d2\");\n                var $products = $('.products', $scope);\n                var $layout_mode = $products.data('layout-mode');\n                \n                if ( $layout_mode === 'masonry' ) {\n                    \/\/ init isotope\n                    var $isotope_products = $products.isotope({\n                        itemSelector: \"li.product\",\n                        layoutMode: $layout_mode,\n                        percentPosition: true\n                    });\n\n                    $isotope_products.imagesLoaded().progress( function() {\n                        $isotope_products.isotope('layout');\n                    })\n                    \n                }\n            });\n        <\/script>\n        \t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-2e0e55b elementor-widget elementor-widget-spacer\" data-id=\"2e0e55b\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"spacer.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<div class=\"elementor-spacer\">\n\t\t\t<div class=\"elementor-spacer-inner\"><\/div>\n\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t","protected":false},"excerpt":{"rendered":"<p>Pneumatische (Druckluft-) Hebeger\u00e4te Pneumatische Hebezeuge f\u00fcr schwerste Lasten (6\u201360 t) | Red Rooster TMH Pneumatische Hebezeuge der TMH-Serie repr\u00e4sentieren die Spitzenklasse f\u00fcr anspruchsvollste industrielle Einsatzbereiche&#8230;.<\/p>\n","protected":false},"author":1,"featured_media":0,"parent":43339,"menu_order":0,"comment_status":"closed","ping_status":"closed","template":"","meta":{"footnotes":""},"class_list":["post-42276","page","type-page","status-publish","hentry"],"_links":{"self":[{"href":"https:\/\/dizalica.hr\/de\/wp-json\/wp\/v2\/pages\/42276","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/dizalica.hr\/de\/wp-json\/wp\/v2\/pages"}],"about":[{"href":"https:\/\/dizalica.hr\/de\/wp-json\/wp\/v2\/types\/page"}],"author":[{"embeddable":true,"href":"https:\/\/dizalica.hr\/de\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/dizalica.hr\/de\/wp-json\/wp\/v2\/comments?post=42276"}],"version-history":[{"count":0,"href":"https:\/\/dizalica.hr\/de\/wp-json\/wp\/v2\/pages\/42276\/revisions"}],"up":[{"embeddable":true,"href":"https:\/\/dizalica.hr\/de\/wp-json\/wp\/v2\/pages\/43339"}],"wp:attachment":[{"href":"https:\/\/dizalica.hr\/de\/wp-json\/wp\/v2\/media?parent=42276"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}